{"id":1600,"date":"2025-05-12T14:06:22","date_gmt":"2025-05-12T12:06:22","guid":{"rendered":"https:\/\/www.df.unipi.it\/people\/nicolo-donato\/"},"modified":"2026-07-12T02:02:20","modified_gmt":"2026-07-12T00:02:20","slug":"nicolo-donato","status":"publish","type":"people","link":"https:\/\/www.df.unipi.it\/en\/people\/nicolo-donato\/","title":{"rendered":"NICOLO&#8217; DONATO"},"author":1,"featured_media":0,"template":"","typology":[76],"class_list":["post-1600","people","type-people","status-publish","hentry","typology-docenti-e-ricercatori"],"acf":{"cognome":"NICOLO'","nome":"DONATO","matricola":"009791","email":"donato.nicolo@unipi.it","telefono":"0502214311","sito_personale":"","ssd":"PHYS-01\/A","settore":"Fisica Sperimentale delle Interazioni Fondamentali e Applicazioni","chiave":4303,"tipo":"DOC","codice_ruolo":"PA","inquadramento":"-","profilo":"Non Assegnato","status":"","qualifica":"","esterno":false,"non_in_servizio":false,"emerito":false,"ciclo_dottorato":"","relatore":"","gruppi_ricerca":"","attivita_di_ricerca":"","orcid":"0000-0001-6414-946X","arxiv_orcid":false,"google_scholar":"qp10pAkAAAAJ","nasaads":"","cariche":"","donotsync":false,"attivita_it":"Argomenti di ricerca in Fisica sperimentale delle Alte Energie\r\n- studio delle caratteristiche dei raggi cosmici e ricerca di monopoli magnetici\r\n- sistema di allerta per eventi di supernova mediante la rivelazioni di neutrini\r\n- oscillazioni di neutrino ai reattori nucleari\r\n- violazione del sapore leptonico in alcuni decadimenti rari dei muoni\r\n- rivelazione dei modi B della radiazione cosmica di fondo in missioni su pallone e satellite\r\n\r\nEsperimenti svolti (o in corso di svolgimento) ed attivit\u00e0 correlate\r\n- MACRO\r\n-- calibrazione del rivelatiore a scintillazione e del sistema di trigger\r\n\r\n- CHOOZ\r\n-- caratterizzazione dei foto-sensori (tubi fotomoltiplicatori) del rivelatore a scintillazione\r\n-- simulazione Monte Carlo della sorgente e del rivelatore dei neutrini, stima dell'efficienza e della reiezione dei fondi\r\n-- costruzione e calibrazione dei rivelatore\r\n-- sviluppo ed implementazione su un chip di rete neurale di algoritmi di reconstruzione veloce di eventi a livello di trigger\r\n-- scruttura del codice di acquisizione dati on-line\r\n-- analisi dati, ricostruzione off-line di eventi, confronti degli spettri misurati con l'atteso, calcolo della sensibilit\u00e0 sperimentale, determinazione degli intervalli di confidenza nello spazio dei parametri delle oscillazioni di neutrino\r\n\r\n- MEG (sia fase I che II)\r\n-- progetto e costruzione di un prototipo del rivelatore \"time-of-flight\"\r\n-- simulazione, R&D, costruzione e test del rivelatore a Xenon Liquido\r\n-- settaggio e calibrazione dei rivelatori a Xenon Liquido (sia prototipi che rivelatore finale)\r\n-- progetto, disegno, costruzione e test del sistema di trigger ed acquisizione dati (TDAQ)\r\n-- sviluppo ed implementazione su FPGA di algoritmi di ricostruzione on-line di eventi a livello di trigger\r\n-- analisi dati off-line, sviluppo di codice per ricostruzione di eventi e calcolo delle efficienze di selezione\r\n-- simulazione dell'upgrade del rivelatore verso l'inizio della fase II\r\n-- costruzione della camera a deriva dello spettrometro magnetico di fase II\r\n\r\n- LSPE, LiteBIRD\r\n-- sviluppo e test del sistema elettronico di lettura, mediante tecnica di Frequency Domain Multiplexing (FDM), accoppiato a sensori Transition-Edge (TES) \r\n\r\nIncarica di responsabilit\u00e0 scientifica\/gestionale ricoperti\r\n- CHOOZ: coordinatore analisi off-line\r\n- MEG, fase I: responsabile trigger (sia costruzione hardware che sviluppo firmware), Run coordinator, responsabili locale per l'INFN\r\n-LiteBIRD: responsabile locale del gruppo UniPi partner del progetto denominato \u201cPartecipazione italiana alla fase A di LiteBIRD\u201d, finanziato dall'Agenzia Spaziale Italiana (bando ASI F84I20000230005); responsabile scientifico del Working Package 3.5 (\u201cTest and integration\u201d) nell'ambito del progeto denominato \u201cSviluppo di sensori TES antenna-coupled\", finanziato da ASI (partner INFN-UniGe-UniPi) sull'accordo quadro n. 2020-25-HH.0.\r\n\r\n\r\n","attivita_en":"Research topics in experimental High Energy Physics\r\n- cosmic ray study and magnetic monopoles search\r\n- supernova alert by early neutrino detection\r\n- neutrino oscillations from nuclear reactors\r\n- charged lepton flavor violation in rare muon decays\r\n- detection of B-modes of Cosmic Microwave Background in both balloon-borne and satellite-based missions\r\n\r\nCarried-out experiments and activities\r\n- MACRO\r\n-- calibration of the scintillation detector and read-out trigger\r\n\r\n- CHOOZ\r\n-- characterization of photon sensors in scintillation detectors\r\n-- simulation of both neutrino source (reactors) and detector, signal efficiency and background rejection estimation\r\n-- detector assembly and calibration\r\n-- development and installation of on-chip neural-network algorithms for fast event reconstruction and trigger\r\n-- setup of the on-line data acquisition system\r\n-- data analysis, event reconstruction, comparison of measured versus expected yields, sensitivity computation, extraction of confidence intervals in neutrino oscillation parameter space\r\n\r\n- MEG (both phase I and II)\r\n-- design and construction of a prototype of the time-of-flight detector\r\n-- simulation, R&D, construction and test of the Liquid Xenon detector\r\n-- setup and calibration of Liquid Xenon detectors (both prototypes and final detector)\r\n-- planning, design, construction and test of trigger and acquisition (TDAQ) system\r\n-- development and implementation of FPGA-based firmware algorithms for online fast event reconstruction at a trigger level (both phase I and II)\r\n-- data offline analysis, development of tools for both event reconstruction and efficiency evaluation\r\n-- simulation of detector upgrades towards phase II\r\n-- construction of the drift chamber of MEG phase II magnetic spectrometer\r\n\r\n- LSPE, LiteBIRD\r\n-- development and test of Frequency Domain Multiplexing (FDM) electronics readout system coupled to Transition-Edge Sensors (TES) \r\n\r\nResponsibility tasks\r\n- CHOOZ: offline analysis coordination\r\n- MEG, phase I: trigger (both hardware construction and firmware algorithms), Run coordination, INFN-Pi group leadership\r\n-LiteBIRD: local responsible for UniPi group involved as a partner of the project named \u201cPartecipazione italiana alla fase A di LiteBIRD\u201d, granted by Agenzia Spaziale Italiana (ASI tender F84I20000230005); scientific responsible of Working Package 3.5 (\u201cTest and integration\u201d) in the frame of the project named \u201cSviluppo di sensori TES antenna-coupled\", granted by ASI-INFN-UniGe-UniPi agreement n. 2020-25-HH.0.\r\n\r\n\r\n\r\n","sito_dottorato":""},"jetpack_sharing_enabled":true,"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.df.unipi.it\/en\/wp-json\/wp\/v2\/people\/1600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.df.unipi.it\/en\/wp-json\/wp\/v2\/people"}],"about":[{"href":"https:\/\/www.df.unipi.it\/en\/wp-json\/wp\/v2\/types\/people"}],"author":[{"embeddable":true,"href":"https:\/\/www.df.unipi.it\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/www.df.unipi.it\/en\/wp-json\/wp\/v2\/media?parent=1600"}],"wp:term":[{"taxonomy":"typology","embeddable":true,"href":"https:\/\/www.df.unipi.it\/en\/wp-json\/wp\/v2\/typology?post=1600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}