{"id":1116,"date":"2024-03-12T11:07:41","date_gmt":"2024-03-12T09:07:41","guid":{"rendered":"https:\/\/www.df.unipi.it\/terza-missione\/?p=1116"},"modified":"2024-04-16T09:32:12","modified_gmt":"2024-04-16T07:32:12","slug":"ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator","status":"publish","type":"post","link":"https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/","title":{"rendered":"Ripartono gli incontri Fisica dell\u2019Area Pontecorvo. Primo incontro: \u201cL&#8217;altra Antimateria: esperimenti all&#8217;Antiproton Decelerator\u201d"},"content":{"rendered":"\n<p>Il <strong>13 marzo 2024, in Aula Magna Fratelli Pontecorvo, alle ore 17:00, <\/strong>riprender\u00e0 il ciclo di incontri di Fisica dell\u2019Area Pontecorvo.<\/p>\n\n\n\n<p>Il primo incontro, dal titolo \u201c<strong>L\u2019altra antimateria: esperimenti all\u2019antiproton decelerator<\/strong>\u201d, sar\u00e0 tenuto da <strong>Simone Stracka<\/strong>, ricercatore dell\u2019INFN di Pisa.<\/p>\n\n\n\n<p><strong>Abstract<\/strong>: Da quasi un secolo i fisici si arrovellano sull&#8217;antimateria, l&#8217;immagine speculare della materia. Ai moderni acceleratori vengono prodotte grandi quantit\u00e0 di particelle e antiparticelle per cercarne le differenze di comportamento in processi sempre pi\u00f9 rari. In questo Colloquio verr\u00e0 invece presentata una strada meno battuta: selezionare alcuni tra i processi pi\u00f9 comuni e meglio studiati nella materia, come le transizioni tra i livelli energetici degli atomi, e riprodurne l&#8217;equivalente in antimateria per studiare anche quello con altissima precisione. Verr\u00e0 quindi mostrata una selezione degli esperimenti in corso all&#8217;Antimatter Factory del CERN e di risultati recenti.<\/p>\n\n\n\n<p>Per maggiori informazioni sull\u2019evento, <a href=\"https:\/\/www.df.unipi.it\/wp-content\/uploads\/2024\/03\/2024Primavera-LocandinePontecorvo-13Mar2024-v1-1-1.pdf\">consulta la locandina<\/a>.<\/p>\n\n\n\n<p>I prossimi incontri sono previsti per:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>il 17 aprile 2024, dal titolo \u201c<strong>Batterie quantistiche: da ricerca di base a un progetto industriale<\/strong>\u201d<\/li>\n\n\n\n<li>il 22 maggio 2024, dal titolo \u201c<strong>Raggi cosmici nella Galassia<\/strong>\u201d.<\/li>\n<\/ul>\n\n\n\n<p>Consulta il calendario di tutti gli \u201cIncontri di Fisica dell\u2019Area Pontecorvo\u201d: <a href=\"https:\/\/www.df.unipi.it\/wp-content\/uploads\/2024\/03\/2024Primavera-LocandinePontecorvo-all-v1.pdf\">https:\/\/www.df.unipi.it\/wp-content\/uploads\/2024\/03\/2024Primavera-LocandinePontecorvo-all-v1.pdf<\/a>.<\/p>\n\n\n\n<p>Il comitato organizzatore dei Colloquia Pontecorvo \u00e8 costituito da Aafke Kraan (INFN-Pisa), Jacopo&nbsp; Pinzino (INFN-Pisa), Laura Elisa Marcucci, Massimiliano Razzano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 13 marzo 2024, in Aula Magna Fratelli Pontecorvo, alle ore 17:00, riprender\u00e0 il ciclo di incontri di Fisica dell\u2019Area&hellip;<\/p>\n<p><a class=\"btn btn-dark btn-sm unipi-read-more-link\" href=\"https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/\">Leggi tutto&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":609,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-1116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ripartono gli incontri Fisica dell\u2019Area Pontecorvo. Primo incontro: \u201cL&#039;altra Antimateria: esperimenti all&#039;Antiproton Decelerator\u201d - Terza missione<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ripartono gli incontri Fisica dell\u2019Area Pontecorvo. Primo incontro: \u201cL&#039;altra Antimateria: esperimenti all&#039;Antiproton Decelerator\u201d - Terza missione\" \/>\n<meta property=\"og:description\" content=\"Il 13 marzo 2024, in Aula Magna Fratelli Pontecorvo, alle ore 17:00, riprender\u00e0 il ciclo di incontri di Fisica dell\u2019Area&hellip;Leggi tutto...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/\" \/>\n<meta property=\"og:site_name\" content=\"Terza missione\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-12T09:07:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-16T07:32:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.df.unipi.it\/terza-missione\/wp-content\/uploads\/sites\/7\/2024\/03\/Incontri-Fisica.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1381\" \/>\n\t<meta property=\"og:image:height\" content=\"231\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\\\/\"},\"author\":{\"name\":\"redazione\",\"@id\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/#\\\/schema\\\/person\\\/eda6875d6346abb03b633a7ad228df3f\"},\"headline\":\"Ripartono gli incontri Fisica dell\u2019Area Pontecorvo. Primo incontro: \u201cL&#8217;altra Antimateria: esperimenti all&#8217;Antiproton Decelerator\u201d\",\"datePublished\":\"2024-03-12T09:07:41+00:00\",\"dateModified\":\"2024-04-16T07:32:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\\\/\"},\"wordCount\":234,\"image\":{\"@id\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/03\\\/Pontecorvo-Colloquia-1.png\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\\\/\",\"url\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\\\/\",\"name\":\"Ripartono gli incontri Fisica dell\u2019Area Pontecorvo. Primo incontro: \u201cL'altra Antimateria: esperimenti all'Antiproton Decelerator\u201d - Terza missione\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/03\\\/Pontecorvo-Colloquia-1.png\",\"datePublished\":\"2024-03-12T09:07:41+00:00\",\"dateModified\":\"2024-04-16T07:32:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/#\\\/schema\\\/person\\\/eda6875d6346abb03b633a7ad228df3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/03\\\/Pontecorvo-Colloquia-1.png\",\"contentUrl\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/03\\\/Pontecorvo-Colloquia-1.png\",\"width\":1906,\"height\":295},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ripartono gli incontri Fisica dell\u2019Area Pontecorvo. Primo incontro: \u201cL&#8217;altra Antimateria: esperimenti all&#8217;Antiproton Decelerator\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/#website\",\"url\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/\",\"name\":\"Terza missione\",\"description\":\"Dipartimento di Matematica - Universit\u00e0 di Pisa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/#\\\/schema\\\/person\\\/eda6875d6346abb03b633a7ad228df3f\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5a6ecd39c9d2ef1c6cb946645f39c2cef1cb4494966af158c23ed5c93daf30b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5a6ecd39c9d2ef1c6cb946645f39c2cef1cb4494966af158c23ed5c93daf30b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5a6ecd39c9d2ef1c6cb946645f39c2cef1cb4494966af158c23ed5c93daf30b?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\\\/\\\/www.df.unipi.it\\\/terza-missione\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ripartono gli incontri Fisica dell\u2019Area Pontecorvo. Primo incontro: \u201cL'altra Antimateria: esperimenti all'Antiproton Decelerator\u201d - Terza missione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/","og_locale":"it_IT","og_type":"article","og_title":"Ripartono gli incontri Fisica dell\u2019Area Pontecorvo. Primo incontro: \u201cL'altra Antimateria: esperimenti all'Antiproton Decelerator\u201d - Terza missione","og_description":"Il 13 marzo 2024, in Aula Magna Fratelli Pontecorvo, alle ore 17:00, riprender\u00e0 il ciclo di incontri di Fisica dell\u2019Area&hellip;Leggi tutto...","og_url":"https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/","og_site_name":"Terza missione","article_published_time":"2024-03-12T09:07:41+00:00","article_modified_time":"2024-04-16T07:32:12+00:00","og_image":[{"width":1381,"height":231,"url":"https:\/\/www.df.unipi.it\/terza-missione\/wp-content\/uploads\/sites\/7\/2024\/03\/Incontri-Fisica.png","type":"image\/png"}],"author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/#article","isPartOf":{"@id":"https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/"},"author":{"name":"redazione","@id":"https:\/\/www.df.unipi.it\/terza-missione\/#\/schema\/person\/eda6875d6346abb03b633a7ad228df3f"},"headline":"Ripartono gli incontri Fisica dell\u2019Area Pontecorvo. Primo incontro: \u201cL&#8217;altra Antimateria: esperimenti all&#8217;Antiproton Decelerator\u201d","datePublished":"2024-03-12T09:07:41+00:00","dateModified":"2024-04-16T07:32:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/"},"wordCount":234,"image":{"@id":"https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/#primaryimage"},"thumbnailUrl":"https:\/\/www.df.unipi.it\/terza-missione\/wp-content\/uploads\/sites\/7\/2023\/03\/Pontecorvo-Colloquia-1.png","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/","url":"https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/","name":"Ripartono gli incontri Fisica dell\u2019Area Pontecorvo. Primo incontro: \u201cL'altra Antimateria: esperimenti all'Antiproton Decelerator\u201d - Terza missione","isPartOf":{"@id":"https:\/\/www.df.unipi.it\/terza-missione\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/#primaryimage"},"image":{"@id":"https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/#primaryimage"},"thumbnailUrl":"https:\/\/www.df.unipi.it\/terza-missione\/wp-content\/uploads\/sites\/7\/2023\/03\/Pontecorvo-Colloquia-1.png","datePublished":"2024-03-12T09:07:41+00:00","dateModified":"2024-04-16T07:32:12+00:00","author":{"@id":"https:\/\/www.df.unipi.it\/terza-missione\/#\/schema\/person\/eda6875d6346abb03b633a7ad228df3f"},"breadcrumb":{"@id":"https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/#primaryimage","url":"https:\/\/www.df.unipi.it\/terza-missione\/wp-content\/uploads\/sites\/7\/2023\/03\/Pontecorvo-Colloquia-1.png","contentUrl":"https:\/\/www.df.unipi.it\/terza-missione\/wp-content\/uploads\/sites\/7\/2023\/03\/Pontecorvo-Colloquia-1.png","width":1906,"height":295},{"@type":"BreadcrumbList","@id":"https:\/\/www.df.unipi.it\/terza-missione\/ripartono-gli-incontri-fisica-dellarea-pontecorvo-primo-incontro-laltra-antimateria-esperimenti-allantiproton-decelerator\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.df.unipi.it\/terza-missione\/"},{"@type":"ListItem","position":2,"name":"Ripartono gli incontri Fisica dell\u2019Area Pontecorvo. Primo incontro: \u201cL&#8217;altra Antimateria: esperimenti all&#8217;Antiproton Decelerator\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.df.unipi.it\/terza-missione\/#website","url":"https:\/\/www.df.unipi.it\/terza-missione\/","name":"Terza missione","description":"Dipartimento di Matematica - Universit\u00e0 di Pisa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.df.unipi.it\/terza-missione\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.df.unipi.it\/terza-missione\/#\/schema\/person\/eda6875d6346abb03b633a7ad228df3f","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e5a6ecd39c9d2ef1c6cb946645f39c2cef1cb4494966af158c23ed5c93daf30b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e5a6ecd39c9d2ef1c6cb946645f39c2cef1cb4494966af158c23ed5c93daf30b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5a6ecd39c9d2ef1c6cb946645f39c2cef1cb4494966af158c23ed5c93daf30b?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/www.df.unipi.it\/terza-missione\/author\/redazione\/"}]}},"jetpack_featured_media_url":"https:\/\/www.df.unipi.it\/terza-missione\/wp-content\/uploads\/sites\/7\/2023\/03\/Pontecorvo-Colloquia-1.png","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 21:18:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.df.unipi.it\/terza-missione\/wp-json\/wp\/v2\/posts\/1116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.df.unipi.it\/terza-missione\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.df.unipi.it\/terza-missione\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.df.unipi.it\/terza-missione\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.df.unipi.it\/terza-missione\/wp-json\/wp\/v2\/comments?post=1116"}],"version-history":[{"count":5,"href":"https:\/\/www.df.unipi.it\/terza-missione\/wp-json\/wp\/v2\/posts\/1116\/revisions"}],"predecessor-version":[{"id":1123,"href":"https:\/\/www.df.unipi.it\/terza-missione\/wp-json\/wp\/v2\/posts\/1116\/revisions\/1123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.df.unipi.it\/terza-missione\/wp-json\/wp\/v2\/media\/609"}],"wp:attachment":[{"href":"https:\/\/www.df.unipi.it\/terza-missione\/wp-json\/wp\/v2\/media?parent=1116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.df.unipi.it\/terza-missione\/wp-json\/wp\/v2\/categories?post=1116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.df.unipi.it\/terza-missione\/wp-json\/wp\/v2\/tags?post=1116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}